{"id":421,"date":"2022-09-06T18:33:44","date_gmt":"2022-09-06T18:33:44","guid":{"rendered":"https:\/\/anabosco.com\/?page_id=421"},"modified":"2023-02-09T18:22:58","modified_gmt":"2023-02-09T18:22:58","slug":"espacados","status":"publish","type":"page","link":"https:\/\/anabosco.com\/en\/espacados\/","title":{"rendered":"Spaced teeth"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"421\" class=\"elementor elementor-421\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c3f0957 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c3f0957\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7aeaf423\" data-id=\"7aeaf423\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-586ab1b8 elementor-widget elementor-widget-heading\" data-id=\"586ab1b8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Spaced teeth<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41d5f9e\" data-id=\"41d5f9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7629ee99 elementor-icon-list--layout-inline elementor-align-right elementor-mobile-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7629ee99\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/anabosco.com\/en\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Spaced teeth<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74dda2f6 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74dda2f6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52763967\" data-id=\"52763967\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad97634 elementor-widget elementor-widget-text-editor\" data-id=\"ad97634\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conhe\u00e7a nossos casos de sucesso com nossas solu\u00e7\u00f5es:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380d97a5 elementor-align-left elementor-mobile-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"380d97a5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#agenesia\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Agenesis<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#diastema-acrescimos\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Diastema closed with composite bonding<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#diastema-facetas\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Diastema closed with composite veneers<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#diastema-posteriores\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Diastema closed in posterior teeth<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#angulo-incisal\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00e2ngulo incisal<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#triangulo-negro\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Black triangle<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-57cc74a3\" data-id=\"57cc74a3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28385359 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28385359\" data-element_type=\"section\" id=\"agenesia\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69e6d4a4\" data-id=\"69e6d4a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-453a750d animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"453a750d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Treatment<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2196c246 elementor-widget elementor-widget-heading\" data-id=\"2196c246\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agenesis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58c03435 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"58c03435\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dental agenesis is a congenital abnormality (which occurs before birth) where one or more teeth do not develop. Composite is a very conservative option, especially for younger patients, as it can provide harmony to their smile. Should the patient desire orthodontic treatment or implants in the future, the composite can simply be removed as no drilling was done and the teeth are intact.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ef0453b elementor-align-center elementor-tablet-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"3ef0453b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/silver-ibex-541238.hostingersite.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ba45d55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ba45d55\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-281d03fe\" data-id=\"281d03fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f27500a elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"4f27500a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module___6a047cca55e80\"  data-grid=\"masonry\" data-id=\"jeg_module___6a047cca55e80\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4714-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4714-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4714-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4714-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4714-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4714-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4966-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4966-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4966-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4966-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4966-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4966-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4714-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_4714-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4714-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4714-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4714-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4714-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4966-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_4966-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4966-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4966-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4966-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4966-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-585d5e48\" data-id=\"585d5e48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fd32a67 elementor-widget elementor-widget-heading\" data-id=\"4fd32a67\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7463f5f8 elementor-widget elementor-widget-text-editor\" data-id=\"7463f5f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Both of the upper lateral incisors were missing in this young teenager. In that moment, the family opted for treatment with composite as it is a reversible and conservative option.<\/p><p>In this case, composite bonding was done with the aim of closing the gaps and masking the pointy canines by making them more rectangular and simulating the shape of the missing lateral incisors.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f16addc elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f16addc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2f884584\" data-id=\"2f884584\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-458235f elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"458235f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__1_6a047cca582ed\"  data-grid=\"masonry\" data-id=\"jeg_module__1_6a047cca582ed\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b902eee\" data-id=\"b902eee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e27e5b1 elementor-widget elementor-widget-heading\" data-id=\"7e27e5b1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-013904c elementor-widget elementor-widget-text-editor\" data-id=\"013904c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>This young teenager presented with agenesis of the right lateral incisor, and her left lateral incisor was cone-shaped (also known as a peg tooth).<\/p><p>The left central incisor had a composite filling done due to a fracture. The family opted for treatment with composite veneers of the front six teeth.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5cdc6352 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cdc6352\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1ad32628\" data-id=\"1ad32628\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6465394a elementor-widget elementor-widget-heading\" data-id=\"6465394a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66617088 elementor-widget elementor-widget-text-editor\" data-id=\"66617088\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>This young teenager presented with agenesis of the right lateral incisor, and her left lateral incisor was cone-shaped (also known as a peg tooth).<\/p><p>The left central incisor had a composite filling done due to a fracture. The family opted for treatment with composite veneers of the front six teeth.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5549e52\" data-id=\"5549e52\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f3074f0 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"5f3074f0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__2_6a047cca5a4e3\"  data-grid=\"masonry\" data-id=\"jeg_module__2_6a047cca5a4e3\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7371-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_7776-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7371-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_7776-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f5705b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f5705b0\" data-element_type=\"section\" id=\"diastema-acrescimos\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b2869f6\" data-id=\"4b2869f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eca9bc animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1eca9bc\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Treatment<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15eddc28 elementor-widget elementor-widget-heading\" data-id=\"15eddc28\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diastema Treated With Composite Bonding<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f721819 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"3f721819\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diastemas are gaps between teeth that can be closed or reduced with composite. When teeth have the appropriate length, the composite can be added just in between both teeth with the objective of closing or reducing the space between them.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c381b elementor-align-center elementor-tablet-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6c381b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/silver-ibex-541238.hostingersite.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2527add8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2527add8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e002cee\" data-id=\"e002cee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c4cb6ec elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"2c4cb6ec\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__3_6a047cca5bdc6\"  data-grid=\"masonry\" data-id=\"jeg_module__3_6a047cca5bdc6\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3066-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3066-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3066-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3066-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3066-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3066-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3079-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3079-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3079-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3079-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3079-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_3079-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3066-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_3066-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3066-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3066-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3066-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3066-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3079-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_3079-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3079-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3079-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3079-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_3079-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-42ed01c1\" data-id=\"42ed01c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d80b8f2 elementor-widget elementor-widget-heading\" data-id=\"5d80b8f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25584298 elementor-widget elementor-widget-text-editor\" data-id=\"25584298\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Patient presented with gaps between all the upper teeth. Since they were all of normal length, it was only necessary to fill in the gaps with composite bonding in between the teeth. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ae5e31f elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ae5e31f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-72442a1f\" data-id=\"72442a1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d473d6d elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"d473d6d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__4_6a047cca5d31a\"  data-grid=\"masonry\" data-id=\"jeg_module__4_6a047cca5d31a\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5875a709\" data-id=\"5875a709\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-445d0fdd elementor-widget elementor-widget-heading\" data-id=\"445d0fdd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e718f65 elementor-widget elementor-widget-text-editor\" data-id=\"e718f65\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In this case, composite bonding was done to the lower teeth. Patient presented with gaps between the lower teeth. In this case, composite bonding was done to the lower teeth.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-74e792ac elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74e792ac\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4d763523\" data-id=\"4d763523\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a67780f elementor-widget elementor-widget-heading\" data-id=\"3a67780f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fdd9eab elementor-widget elementor-widget-text-editor\" data-id=\"2fdd9eab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Patient presented with gaps between the lower teeth. In this case, composite bonding was done to the lower teeth.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5e3e5e5\" data-id=\"5e3e5e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bb1d6ff elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"4bb1d6ff\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__5_6a047cca5ef65\"  data-grid=\"masonry\" data-id=\"jeg_module__5_6a047cca5ef65\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6652-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6657-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6652-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6657-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58013322 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58013322\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-36f5d9ca\" data-id=\"36f5d9ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87c5bce elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"87c5bce\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__6_6a047cca5fba3\"  data-grid=\"masonry\" data-id=\"jeg_module__6_6a047cca5fba3\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1720-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1720-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1720-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1720-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1720-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1720-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1971-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1971-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1971-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1971-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1971-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1971-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1720-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_1720-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1720-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1720-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1720-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1720-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1971-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_1971-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1971-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1971-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1971-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1971-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-31392390\" data-id=\"31392390\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-435f13c8 elementor-widget elementor-widget-heading\" data-id=\"435f13c8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 3<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef15d7e elementor-widget elementor-widget-text-editor\" data-id=\"1ef15d7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Patient presented with a small gap between the lateral incisor and the canine that was bothersome. This gap was closed with composite bonding and without any drilling to the teeth.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29317f5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29317f5d\" data-element_type=\"section\" id=\"diastema-facetas\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39903db5\" data-id=\"39903db5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18a7b407 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"18a7b407\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Treatment<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e5f617b elementor-widget elementor-widget-heading\" data-id=\"6e5f617b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diastema Treated With Veneers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e51de9b elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"7e51de9b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>When teeth with gaps also present with some alterations to the shape, size and colour, an alternative is to correct these with the use of composite veneers. This is when the entire frontal surface of the tooth is covered with composite, which improves the aesthetic look and corrects the imperfections described above.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-214980aa elementor-align-center elementor-tablet-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"214980aa\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/silver-ibex-541238.hostingersite.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-219a9fa9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"219a9fa9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e200d40\" data-id=\"e200d40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2da05449 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"2da05449\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__7_6a047cca61d46\"  data-grid=\"masonry\" data-id=\"jeg_module__7_6a047cca61d46\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1746-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1746-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1746-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1746-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1746-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1746-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_2607-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_2607-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_2607-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_2607-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_2607-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_2607-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1746-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_1746-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1746-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1746-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1746-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1746-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_2607-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_2607-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_2607-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_2607-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_2607-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_2607-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7aae4bfe\" data-id=\"7aae4bfe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b41f965 elementor-widget elementor-widget-heading\" data-id=\"6b41f965\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-441d89c1 elementor-widget elementor-widget-text-editor\" data-id=\"441d89c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In cases where it is necessary to increase both the length and the width of teeth, veneers are highly recommended. This is where the tooth is entirely encased in the restorative material, which can be porcelain or composite. This patient opted for eight composite veneers without any drilling.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b819987 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b819987\" data-element_type=\"section\" id=\"diastema-posteriores\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20cb453b\" data-id=\"20cb453b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b140f92 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1b140f92\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Treatment<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7874b8bb elementor-widget elementor-widget-heading\" data-id=\"7874b8bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diastema on Posterior Teeth<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d456745 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"6d456745\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>When gaps between posterior teeth are not large enough for implants or dental bridges, an alternative to orthodontic treatment is to close or reduce this undesired space with composite bonding <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bc7d717 elementor-align-center elementor-tablet-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"2bc7d717\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/silver-ibex-541238.hostingersite.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-510c82d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"510c82d3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ad47e1b\" data-id=\"5ad47e1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27bd352e elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"27bd352e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__8_6a047cca63e41\"  data-grid=\"masonry\" data-id=\"jeg_module__8_6a047cca63e41\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5517-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5517-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5517-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5517-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5517-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5517-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5555-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5555-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5555-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5555-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5555-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5555-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5517-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_5517-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5517-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5517-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5517-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5517-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5555-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_5555-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5555-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5555-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5555-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5555-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e71ac03 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"e71ac03\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__9_6a047cca64a3b\"  data-grid=\"masonry\" data-id=\"jeg_module__9_6a047cca64a3b\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5538-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5538-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5538-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5538-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5538-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5538-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;320\\&quot; height=\\&quot;213\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5535-2.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5535-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5535-2.jpg 320w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5535-2-300x200.jpg 300w\\&quot; sizes=\\&quot;(max-width: 320px) 100vw, 320px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5538-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_5538-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5538-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5538-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5538-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5538-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\"><\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"213\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5535-2.jpg\" class=\"attachment-large size-large\" alt=\"\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_5535-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5535-2.jpg 320w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5535-2-300x200.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\"><\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4568c91\" data-id=\"4568c91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c17487f elementor-widget elementor-widget-heading\" data-id=\"4c17487f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39a1daea elementor-widget elementor-widget-text-editor\" data-id=\"39a1daea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Patient reported using orthodontic braces for many years, yet the gaps between his upper teeth on both the left and right sides had not closed.<\/p><p>In that moment, the patient was not interested in any sort of orthodontic treatment. The option suggested and subsequently accepted by the patient was to close these gaps with composite.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6aacb23d elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6aacb23d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4f79633b\" data-id=\"4f79633b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0069811 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"0069811\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__10_6a047cca65e3d\"  data-grid=\"masonry\" data-id=\"jeg_module__10_6a047cca65e3d\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-49341c7b\" data-id=\"49341c7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b988504 elementor-widget elementor-widget-heading\" data-id=\"3b988504\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e44c643 elementor-widget elementor-widget-text-editor\" data-id=\"e44c643\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In this case, the patient had her second premolar extracted many years ago, and, over time, the first molar has shifted towards the front. The space was not large enough for an implant. In that moment, the patient was not interested in orthodontic treatment or in drilling her teeth for a fixed dental bridge.<\/p><p>The suggested alternative that the patient agreed to was to reduce the space with composite bonding. Some composite bonding was also done to the front teeth.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-17c30cb9 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17c30cb9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20ceda3\" data-id=\"20ceda3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-728926b4 elementor-widget elementor-widget-heading\" data-id=\"728926b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-561b3115 elementor-widget elementor-widget-text-editor\" data-id=\"561b3115\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In this case, the patient had her second premolar extracted many years ago, and, over time, the first molar has shifted towards the front. The space was not large enough for an implant. In that moment, the patient was not interested in orthodontic treatment or in drilling her teeth for a fixed dental bridge.<\/p><p>The suggested alternative that the patient agreed to was to reduce the space with composite bonding. Some composite bonding was also done to the front teeth.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4e7f6614\" data-id=\"4e7f6614\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11e89cc4 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"11e89cc4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__11_6a047cca67885\"  data-grid=\"masonry\" data-id=\"jeg_module__11_6a047cca67885\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4833-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_5409-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4833-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_5409-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-716bd03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"716bd03\" data-element_type=\"section\" id=\"angulo-incisal\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1a5b6d\" data-id=\"e1a5b6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0984450 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0984450\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Treatment<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45105d5 elementor-widget elementor-widget-heading\" data-id=\"45105d5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Incisal angle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e033735 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"e033735\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>This term also describes a gap between teeth but differs from a diastema in that it refers to a small space between the edges of the teeth.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7202afa elementor-align-center elementor-tablet-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"7202afa\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/silver-ibex-541238.hostingersite.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d101628 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d101628\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-48c533d\" data-id=\"48c533d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51b30b9 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"51b30b9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__12_6a047cca690e8\"  data-grid=\"masonry\" data-id=\"jeg_module__12_6a047cca690e8\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1307-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1307-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1307-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1307-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1307-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1307-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1317-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1317-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1317-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1317-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1317-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_1317-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1307-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_1307-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1307-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1307-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1307-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1307-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1317-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_1317-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1317-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1317-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1317-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_1317-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b4496e\" data-id=\"6b4496e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f392e39 elementor-widget elementor-widget-heading\" data-id=\"f392e39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de342c8 elementor-widget elementor-widget-text-editor\" data-id=\"de342c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Patient was bothered with the gaps, the shapes and the misalignment of her teeth. She opted for composite bonding with no drilling. In one sitting, it was possible to close the gaps, give a new shape to her smile and disguise the protruding lateral incisors.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-708fd4b elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"708fd4b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e4f7109\" data-id=\"e4f7109\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a1d379 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"8a1d379\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__13_6a047cca6a577\"  data-grid=\"masonry\" data-id=\"jeg_module__13_6a047cca6a577\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cadecd0\" data-id=\"cadecd0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfcce1b elementor-widget elementor-widget-heading\" data-id=\"bfcce1b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-847d582 elementor-widget elementor-widget-text-editor\" data-id=\"847d582\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A young lady presented with very yellow teeth and was unhappy with their shape. The patient opted for whitening and composite bonding applied to specific areas of the teeth in a very conservative manner. At the end of treatment, patient was happy and objectives were achieved.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-45cd1f3 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45cd1f3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-95b05b6\" data-id=\"95b05b6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e4d733 elementor-widget elementor-widget-heading\" data-id=\"4e4d733\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8b9e64 elementor-widget elementor-widget-text-editor\" data-id=\"f8b9e64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A young lady presented with very yellow teeth and was unhappy with their shape. The patient opted for whitening and composite bonding applied to specific areas of the teeth in a very conservative manner. At the end of treatment, patient was happy and objectives were achieved.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5afc81d\" data-id=\"5afc81d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4e5a02 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"b4e5a02\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__14_6a047cca6c016\"  data-grid=\"masonry\" data-id=\"jeg_module__14_6a047cca6c016\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_4114-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;800\\&quot; height=\\&quot;534\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2-1024x683.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2-1024x683.jpg 1024w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2-300x200.jpg 300w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2-768x512.jpg 768w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_0001-2-2.jpg 1068w\\&quot; sizes=\\&quot;(max-width: 800px) 100vw, 800px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_4114-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2-1024x683.jpg 1024w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2-300x200.jpg 300w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2-768x512.jpg 768w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_0001-2-2.jpg 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2aa4c66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2aa4c66\" data-element_type=\"section\" id=\"triangulo-negro\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-992b4e3\" data-id=\"992b4e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-414577e animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"414577e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Treatment<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a97e7a elementor-widget elementor-widget-heading\" data-id=\"0a97e7a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Black Triangle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96c977b elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"96c977b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Black triangles are spaces that appear between teeth near to the gum. There are many reasons for this and depending on the height of your smile it can be the cause of an aesthetic concern. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68ed05e elementor-align-center elementor-tablet-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"68ed05e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/silver-ibex-541238.hostingersite.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-965722d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"965722d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-efd2d82\" data-id=\"efd2d82\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e14702 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"6e14702\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__15_6a047cca6d889\"  data-grid=\"masonry\" data-id=\"jeg_module__15_6a047cca6d889\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;320\\&quot; height=\\&quot;213\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6064-2.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6064-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6064-2.jpg 320w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6064-2-300x200.jpg 300w\\&quot; sizes=\\&quot;(max-width: 320px) 100vw, 320px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;320\\&quot; height=\\&quot;213\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6076-2.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6076-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6076-2.jpg 320w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6076-2-300x200.jpg 300w\\&quot; sizes=\\&quot;(max-width: 320px) 100vw, 320px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"213\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6064-2.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_6064-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6064-2.jpg 320w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6064-2-300x200.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"213\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6076-2.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_6076-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6076-2.jpg 320w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6076-2-300x200.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c62d051 elementor-invisible elementor-widget elementor-widget-jkit_gallery\" data-id=\"c62d051\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"jkit_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-gallery layout-overlay jeg_module__16_6a047cca6e3e4\"  data-grid=\"masonry\" data-id=\"jeg_module__16_6a047cca6e3e4\" data-per-page=\"2\" data-load-more=\"0\" data-current-loaded=\"2\" data-count-items=\"2\" data-animation-duration=\"500\" data-no-more=\"No More Item\" data-items=\"[&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;320\\&quot; height=\\&quot;213\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6067-2.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;Before\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6067-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6067-2.jpg 320w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6067-2-300x200.jpg 300w\\&quot; sizes=\\&quot;(max-width: 320px) 100vw, 320px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;Before&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;,&quot;&lt;div class=\\&quot;gallery-item-wrap \\&quot;&gt; &lt;div class=\\&quot;grid-item\\&quot;&gt;&lt;div class=\\&quot;thumbnail-wrap\\&quot;&gt;&lt;img width=\\&quot;320\\&quot; height=\\&quot;213\\&quot; src=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6069-2.jpg\\&quot; class=\\&quot;attachment-large size-large\\&quot; alt=\\&quot;After\\&quot; url=\\&quot;https:\\\/\\\/silver-ibex-541238.hostingersite.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6069-2.jpg\\&quot; source=\\&quot;library\\&quot; srcset=\\&quot;https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6069-2.jpg 320w, https:\\\/\\\/anabosco.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_6069-2-300x200.jpg 300w\\&quot; sizes=\\&quot;(max-width: 320px) 100vw, 320px\\&quot; \\\/&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;caption-wrap style-overlay overlay-slide\\&quot;&gt; &lt;div class=\\&quot;item-hover-bg\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;item-caption-over\\&quot;&gt; &lt;h5 class=\\&quot;item-title\\&quot;&gt;After&lt;\\\/h5&gt; &lt;div class=\\&quot;item-content\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt; &lt;div class=\\&quot;caption-head\\&quot;&gt;&lt;\\\/div&gt; &lt;div class=\\&quot;caption-category\\&quot;&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&lt;\\\/div&gt; &lt;\\\/div&gt;&quot;]\">\n            <div class=\"gallery-items\"><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"213\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6067-2.jpg\" class=\"attachment-large size-large\" alt=\"Before\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_6067-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6067-2.jpg 320w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6067-2-300x200.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">Before<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><div class=\"gallery-item-wrap\"> <div class=\"grid-item\"><div class=\"thumbnail-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"213\" src=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6069-2.jpg\" class=\"attachment-large size-large\" alt=\"After\" url=\"https:\/\/silver-ibex-541238.hostingersite.com\/wp-content\/uploads\/2022\/09\/IMG_6069-2.jpg\" source=\"library\" srcset=\"https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6069-2.jpg 320w, https:\/\/anabosco.com\/wp-content\/uploads\/2022\/09\/IMG_6069-2-300x200.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/div><div class=\"caption-wrap style-overlay overlay-slide\"> <div class=\"item-hover-bg\"><\/div> <div class=\"item-caption-over\"> <h5 class=\"item-title\">After<\/h5> <div class=\"item-content\"><\/div> <\/div> <div class=\"caption-head\"><\/div> <div class=\"caption-category\"><\/div> <\/div><\/div> <\/div><\/div>\n            <div class=\"load-more-items\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a216df\" data-id=\"7a216df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ba3be7 elementor-widget elementor-widget-heading\" data-id=\"2ba3be7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Case 1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29ae30f elementor-widget elementor-widget-text-editor\" data-id=\"29ae30f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Patient was very bothered with the gaps between her teeth. Composite bonding was done without any drilling to fill the gaps and improve their appearance. In these cases, absolute isolation with a rubber dam is very important in order to keep a dry field of work and avoid excess amounts of composite next to the gum. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Dentes Espa\u00e7ados Home Dentes Espa\u00e7ados Conhe\u00e7a nossos casos de sucesso com nossas solu\u00e7\u00f5es: Agenesia Diastema fechado com acr\u00e9scimo de resina Diastema fechado com facetas Diastema fechado em dentes posteriores \u00e2ngulo incisal Tri\u00e2ngulo negro Tratamento Agenesia Agenesia dental \u00e9 uma anomalia cong\u00eanita (que ocorre antes do nascimento) onde um ou mais dentes n\u00e3o se formam. A [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"folder":[],"aioseo_notices":[],"class_list":["post-421","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/anabosco.com\/en\/wp-json\/wp\/v2\/pages\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anabosco.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anabosco.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anabosco.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anabosco.com\/en\/wp-json\/wp\/v2\/comments?post=421"}],"version-history":[{"count":9,"href":"https:\/\/anabosco.com\/en\/wp-json\/wp\/v2\/pages\/421\/revisions"}],"predecessor-version":[{"id":1290,"href":"https:\/\/anabosco.com\/en\/wp-json\/wp\/v2\/pages\/421\/revisions\/1290"}],"wp:attachment":[{"href":"https:\/\/anabosco.com\/en\/wp-json\/wp\/v2\/media?parent=421"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/anabosco.com\/en\/wp-json\/wp\/v2\/folder?post=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}